{"id":54525,"date":"2022-05-19T10:57:37","date_gmt":"2022-05-19T08:57:37","guid":{"rendered":"https:\/\/www.edogs.de\/magazin\/?p=54525"},"modified":"2025-02-10T15:28:51","modified_gmt":"2025-02-10T14:28:51","slug":"wespenstich-hund","status":"publish","type":"post","link":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/","title":{"rendered":"Wespenstich beim Hund &#8211; Was nun zu tun ist"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"54525\" class=\"elementor elementor-54525\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-8cf55e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8cf55e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8698a0\" data-id=\"d8698a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac8c6e elementor-widget elementor-widget-text-editor\" data-id=\"4ac8c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Im Sommer sind auch die Wespen wieder aktiv. Spielt der Hund im Garten oder beim Spaziergang auf einer Wiese, kann es schnell zu einem schmerzhaften Kontakt mit den gestreiften Insekten kommen. Der Wespenstich beim Hund erfolgt vor allem in die Schnauze oder die Pfoten. Nicht immer ist der Wespenstich beim Hund harmlos. Reagiert der Hund allergisch auf das Wespengift, kann der Wespenstich beim Hund auch t\u00f6dlich enden.<\/strong><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-dmcheck penci-elbg-activate penci-disSticky penci-structure-20 elementor-section elementor-top-section elementor-element elementor-element-c3785b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3785b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28e824d8\" data-id=\"28e824d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51eb1f17 elementor-widget elementor-widget-text-editor\" data-id=\"51eb1f17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #131313;\">Wespenstich (Hund): Krankheitssteckbrief<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45fe26c2 elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"45fe26c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-temperature-high\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Symptome<\/b>: R\u00f6tungen, <a href=\"https:\/\/www.edogs.de\/magazin\/juckreiz-beim-hund\/\">Juckreiz<\/a>, geschwollenes Gewebe, ggf. allergische Reaktionen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-chart-bar\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Verlauf<\/b>: Akut<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hospital\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Schwere der Erkrankung:<\/b>: Meist unproblematisch<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>H\u00e4ufigkeit<\/b>: Gelegentlich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Vorkommen<\/b>: Bei allen Hunden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-2 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34c11706\" data-id=\"34c11706\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11d2fd1c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"11d2fd1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tint\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Diagnose<\/b>: Bei einem allergischen Schock muss immer sofort ein <strong>Tierarzt<\/strong> verst\u00e4ndigt werden.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-syringe\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Behandlung<\/b>: Apfelessig, <a href=\"https:\/\/www.edogs.de\/magazin\/bachblueten-hunde\/\">Bachbl\u00fcten<\/a>, K\u00fchlen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-heartbeat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Prognose<\/b>: Gute Prognose<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dog\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Ansteckungsgefahr<\/b>: Nicht ansteckend<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-briefcase-medical\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Fachgebiet<\/b>: Dermatologie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-662b0072 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"662b0072\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5283af8f\" data-id=\"5283af8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a37616a elementor-widget elementor-widget-text-editor\" data-id=\"a37616a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Wie kommt es zu einem Wespenstich bei Hunden?<\/h2><p>Hunde sind nicht nur neugierig, die meisten besitzen einen starken <strong>Jagdinstinkt<\/strong>. Fliegen Wespen durch die Wiese, beginnt der Hund, die <strong>Insekten<\/strong> <strong>zu<\/strong> <strong>jagen<\/strong>. Diese f\u00fchlen sich provoziert und starten ebenfalls eine Attacke auf die Schnauze des Hundes. Tritt der Hund direkt auf eine am Boden sitzende Wespe, sticht diese sofort zu, um sich zu verteidigen.\u00a0<\/p><p>Steht die <strong>Futtersch\u00fcssel<\/strong> des Hundes im Garten, werden die Wespen von dem unwiderstehlichen Geruch magisch angezogen. Schlingt der Hund sein Futter hinunter, wird auch die Wespe <strong>verschluckt<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aea4d31 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"aea4d31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWas passiert, wenn mein Hund von einer Wespe gestochen wird?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDer Hund ist irritiert und hat Schmerzen. An der Einstichstelle entsteht eine Schwellung. Da die Wespe den Stachel wieder herauszieht, bleibt kein Fremdk\u00f6rper in der Wunde zur\u00fcck. Das Wespengift breitet sich im Gewebe aus und verursacht Juckreiz.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0779c83 elementor-widget elementor-widget-text-editor\" data-id=\"0779c83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Was passiert mit der Wespe, wenn sie gestochen hat?<\/h3><p>Anders als bei Bienen ist der Stachel der Wespen glatt und besitzt keine Widerhaken. Er kann nach dem Stich und der Abgabe des Wespengifts problemlos von der Wespe wieder aus der Haut gezogen werden. Die Wespe kann <strong>noch einmal zustechen oder wegfliegen<\/strong>. Das Tier stirbt nicht nach dem Stich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2760e2a elementor-widget elementor-widget-text-editor\" data-id=\"2760e2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Unterschiede zwischen Wespen-, Bienen- und Hornissenstichen beim Hund<\/h3><p>Wespen-, Bienen- und Hornissenstiche unterscheiden sich hinsichtlich ihrer <strong>Wirkung<\/strong>, was von der <strong>Art des Giftes<\/strong> und der <strong>Tiefe des Einstichs<\/strong> abh\u00e4ngt. Diese Unterschiede k\u00f6nnen Einfluss auf die Reaktion Ihres Hundes haben:<\/p><ul><li><strong>Wespenstich:<\/strong> Wespen k\u00f6nnen mehrfach zustechen, da sie ihren Stachel nicht verlieren. Das Gift kann starke Schmerzen und Schwellungen verursachen, ist jedoch in der Regel nicht sofort t\u00f6dlich.<\/li><li><strong>Bienenstich:<\/strong> Bienen verlieren ihren Stachel in der Haut, was die Giftmenge erh\u00f6ht. Das verbleibende Giftsekret kann l\u00e4nger wirken und verst\u00e4rkte Schwellungen ausl\u00f6sen.<\/li><li><strong>Hornissenstich:<\/strong> Hornissenstiche gelten als schmerzhafter, da mehr Gift injiziert wird. Dennoch ist ihr Gift chemisch weniger toxisch als das von Wespen. Aufgrund der gr\u00f6\u00dferen Stichwunde ist jedoch eine st\u00e4rkere Gewebereizung m\u00f6glich.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1928f56 elementor-widget elementor-widget-text-editor\" data-id=\"1928f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Wespenstich beim Hund an der Schnauze<\/h2><p>Sticht die Wespe \u00e4u\u00dferlich an den Lefzen oder der Nase,<strong> schwillt das Gewebe als Reaktion auf das Wespengift stark an<\/strong>. Der Stich ist <strong>schmerzhaft<\/strong>. Der Hund reibt die Nase am Boden oder ber\u00fchrt sie immer wieder mit seiner Pfote. Schnelle <strong>K\u00fchlung <\/strong>lindert den Schmerz der Stiche etwas. Bei empfindlichen Hunden kann bei einem Stich im Kopfbereich schnell eine allergische Reaktion auftreten. Symptome davon sind <a href=\"https:\/\/www.edogs.de\/magazin\/erbrechen-beim-hund\/\">Erbrechen<\/a>, Kr\u00e4mpfe und Atemnot der Tiere.<\/p><p>Reagiert der Hund nicht allergisch, ist die Schwellung meistens am n\u00e4chsten Tag nicht mehr zu sehen. Auch die Schmerzen beim Tier sind verschwunden<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fba54e elementor-widget elementor-widget-text-editor\" data-id=\"0fba54e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Ein Wespenstich im Maul ist besonders unangenehm<\/h3><p>Unangenehmer ist es, wenn die Wespe in die Maulh\u00f6hle der Hunde gelangt und in die Zunge oder den Gaumen sticht. Die <strong>Schleimh\u00e4ute schwellen als Reaktion auf das Wespengift schnell an<\/strong>. Der Hund kann nur mehr schwer atmen und droht zu ersticken. Als erste Hilfe k\u00fchlt <a href=\"https:\/\/www.edogs.de\/magazin\/diy-eis-fuer-hunde-selber-machen\/\">Eis<\/a> die Schwellung im Maul. Bei einer Einstichstelle im Maul sollte immer ein <strong>Tierarzt<\/strong> aufgesucht werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a50f1d elementor-widget elementor-widget-text-editor\" data-id=\"4a50f1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Wespenstich beim Hund in der Pfote<\/h3><p>Der Hund l\u00e4uft durch das Gras und jault pl\u00f6tzlich. Er hebt die Pfote und humpelt. Bei der Untersuchung der Haut zwischen den Zehen und Ballen f\u00e4llt die rote Einstichstelle schnell auf. Jetzt ist <strong>K\u00fchlung mit Wasser oder Eis<\/strong> angesagt, damit der Schmerz schnell nachl\u00e4sst und die Schwellung zur\u00fcckgeht.<br \/>Zeigt der Hund auf das Wespengift eine allergische Reaktion, sind \u00fcber den ganzen K\u00f6rper verteilt unglaublich gro\u00dfe <strong>Quaddeln<\/strong> zu sehen. Wurde der Hund mehrmals gestochen, kann es zu einem allergischen Schock kommen.<\/p><div id=\"attachment_54578\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-54578\" class=\"wp-image-54578 size-full\" src=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-in-der-Pfote.jpg\" alt=\"Wespenstich: Hund mit Verbandszeug\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-in-der-Pfote.jpg 600w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-in-der-Pfote-300x200.jpg 300w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-in-der-Pfote-585x390.jpg 585w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-in-der-Pfote-263x175.jpg 263w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-54578\" class=\"wp-caption-text\">Zeigt der Hund auf das Wespengift eine allergische Reaktion, sind \u00fcber den ganzen K\u00f6rper verteilt unglaublich gro\u00dfe Quaddeln zu sehen. Wurde der Hund mehrmals gestochen, kann es zu einem allergischen Schock kommen.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cce3cda elementor-widget elementor-widget-text-editor\" data-id=\"cce3cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Ist ein Wespenstich f\u00fcr Hunde gef\u00e4hrlich?<\/h2><p>Nicht jeder Hund reagiert auf das Wespengift, das bei dem Stich in die Haut injiziert wird, gleich. Ist der Hund nicht allergisch, entsteht nur eine kleine Schwellung, die schmerzt und juckt. Bei einem Stich in die Pfote humpelt der Hund f\u00fcr kurze Zeit. Reagiert der Hund <strong>allergisch<\/strong>, kann der Wespenstich zum Tod vom Tier f\u00fchren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1958be6 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1958be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSind Hunde immun gegen Wespenstiche?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHunde sind nicht immun gegen Wespenstiche. Die Reaktionen auf das Wespengift fallen unterschiedlich stark aus.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9779fe elementor-widget elementor-widget-text-editor\" data-id=\"f9779fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Symptome bei einem Wespenstich beim Hund<\/h3><p>Die Symptome sind<strong> abh\u00e4ngig von der Lokalisation der Stelle des Einstiches<\/strong>. Erfolgte der Wespenstich in die Pfote, humpelt der Hund oder l\u00e4uft auf drei Beinen. Bei Stichen im Mund schwillt die Zunge an. Der Hund erbricht und speichelt. Er bekommt nur schlecht Luft.<\/p><p><strong>Stiche im Kopfbereich sind am gef\u00e4hrlichsten<\/strong>. Das Wespengift gelangt schnell zu den Nerven und verursacht Kr\u00e4mpfe und einen allergischen Schock. Reagiert der Hund nur mit einer Schwellung und R\u00f6tung der Einstichstelle, ist es ausreichend, diese zu k\u00fchlen. Die Symptome verschwinden schon nach wenigen Stunden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70c5d77 elementor-widget elementor-widget-text-editor\" data-id=\"70c5d77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Allergischer Schock<\/h3><p>L\u00f6st der Stich der Wespe eine allergische Reaktion aus, reagiert das <strong>Immunsystem<\/strong> des Hundes besonders stark auf das Wespengift. Der Hund ist unruhig und beginnt zu zittern. Die Schleimh\u00e4ute sind blass. Atmung und Herzschlag sind beschleunigt. Der Puls ist angespannt und schnell. Auf der Haut bilden sich Quaddeln. Der Hund bellt heiser.\u00a0<\/p><p>Durch die Schwellung der Schleimh\u00e4ute im Mund und ein Anschwellen des Kehlkopfdeckels kann der Hund nicht mehr atmen. Er bricht wegen des <strong>Sauerstoffmangels<\/strong> zusammen und wird bewusstlos. Wird der Hund nicht von einem Tierarzt behandelt, stirbt er durch den<a href=\"https:\/\/www.edogs.de\/magazin\/allergie-hund\/\"> allergischen Schock<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7e21f7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d7e21f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie schnell kommt eine allergische Reaktion bei einem Wespenstich bei Hunden?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEine allergische Reaktion auf einen Wespenstich beim Hund tritt innerhalb weniger Minuten nach dem Stich des Insekts auf. Die Atmung f\u00e4llt dem Hund immer schwerer. Er hechelt und wird ohne Hilfe bewusstlos.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b1807 elementor-widget elementor-widget-text-editor\" data-id=\"90b1807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Kann ein Wespenstich beim Hund zu Sp\u00e4tfolgen f\u00fchren?<\/h3><p>Ein Wespenstich ist in den meisten F\u00e4llen harmlos und heilt innerhalb weniger Tage ab. Es gibt jedoch <strong>Umst\u00e4nde, unter denen Sp\u00e4tfolgen auftreten k\u00f6nnen<\/strong>:<\/p><ul><li>Lokale Infektionen durch aufgebrachtes Kratzen oder Knabbern des Hundes<\/li><li>Allergische Sensibilisierung: Wiederholte Stiche k\u00f6nnen zu einer st\u00e4rkeren Reaktion bei k\u00fcnftigen Stichen f\u00fchren, wom\u00f6glich bis hin zum anaphylaktischen Schock.<\/li><li>Bleibende Hautver\u00e4nderungen wie Narben an der Einstichstelle<\/li><li>In seltenen F\u00e4llen k\u00f6nnen \u00fcberm\u00e4\u00dfig starke Schwellungen umliegendes Gewebe sch\u00e4digen<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d735a elementor-widget elementor-widget-text-editor\" data-id=\"21d735a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Behandlung eines Wespenstichs beim Hund<\/h2><p>Tritt keine allergische Reaktion auf, ist es ausreichend, die <strong>Einstichstelle zu k\u00fchlen<\/strong>. Abschwellende Salben lindern den <a href=\"https:\/\/www.edogs.de\/magazin\/juckreiz-beim-hund\/\">Juckreiz<\/a>. Bei st\u00e4rkeren Reaktionen erh\u00e4lt der Hund von einem Tierarzt <strong>Kortison und Antihistaminika<\/strong>.<\/p><p>Bei einem allergischen Schock ben\u00f6tigt der Hund <strong>Infusionen<\/strong>. Eventuell muss der Vierbeiner beatmet werden, bis die Schwellung der Atemwege nachl\u00e4sst<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7477fa6 elementor-widget elementor-widget-text-editor\" data-id=\"7477fa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Erste Hilfe Ma\u00dfnahmen<\/h3><p>Die beste Erste Hilfe ist eine <strong>K\u00fchlung<\/strong> der Einstichstelle. Dazu k\u00f6nnen kaltes Wasser oder Eisw\u00fcrfel verwendet werden. Der Hund sollte beruhigt werden. Bei einem Stich in den Mund helfen kurz eingefrorene Kauknochen oder kaltes Spielzeug. Der Hund kann auch Eis fressen.<\/p><p>Bei einem allergischen Schock muss immer sofort ein <strong>Tierarzt<\/strong> verst\u00e4ndigt werden. Ist der Hund bereits bewusstlos, wird er in eine <strong>stabile<\/strong> <strong>Seitenlage<\/strong> gebracht. Die Atemwege sollten frei bleiben. Nach der \u00dcberpr\u00fcfung der Vitalfunktionen muss der Hund zu einem Tierarzt gebracht werden. Bei der Fahrt sollten immer zwei Personen anwesend sein. Eine Person kann den Kopf und den Brustkorb des Hundes leicht anheben, damit die Atmung erleichtert wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-067eb38 elementor-widget elementor-widget-text-editor\" data-id=\"067eb38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Wann sollte man zum Tierarzt?<\/h3><p>Klingt die Reaktion an der Stichstelle nicht innerhalb von wenigen Stunden ab, muss der Hund von einem Tierarzt behandelt werden. Bei einer <strong>allergischen<\/strong> <strong>Reaktion<\/strong> muss immer ein Tierarzt aufgesucht werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-391f813d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"391f813d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie gef\u00e4hrlich ist ein Wespenstich bei Hunden?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tNormalerweise ist ein Wespenstich beim Hund nicht gef\u00e4hrlich. Die Schwellung und Schmerzen klingen schon nach kurzer Zeit ab. Zeigt der Hund eine allergische Reaktion auf das Wespengift, muss schnell erste Hilfe geleistet werden.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e615f79 elementor-widget elementor-widget-text-editor\" data-id=\"e615f79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Hausmittel<\/h3><p>Hausmittel verringern den Juckreiz, den Schmerz und die Schwellung an der Einstichstelle. Zur K\u00fchlung der Einstichstelle werden <strong>Eisw\u00fcrfel<\/strong> <strong>in ein Tuch<\/strong> gewickelt und auf die Schwellung gelegt. Es k\u00f6nnen auch Cool-Packs verwendet werden.<\/p><ul><li><strong>Bachbl\u00fcten<\/strong> (Rescue Tropfen) helfen dem Hund, den Schock zu bek\u00e4mpfen.\u00a0<\/li><li><strong>Apis D3<\/strong> verringert die Reaktion auf das Wespengift und die Schwellung. Bei Schwellung der Schleimhaut im Mund kann Lachesis D4 eingesetzt werden.<\/li><li><strong>Apfelessig<\/strong> wirkt k\u00fchlend und reduziert die Schmerzen.<\/li><li>Eine klein gehackte und gequetschte <strong>Zwiebel<\/strong> bewirkt ebenfalls eine K\u00fchlung und lindert die Schwellung der Haut. Der Saft der Zwiebel verhindert, dass an der Einstichstelle eine Entz\u00fcndung entsteht.\u00a0<\/li><li>Ist noch keine Schwellung entstanden, hilft <strong>hei\u00dfes<\/strong> <strong>Wasser<\/strong>, die Ausbreitung des Wespengiftes zu verhindern. Wespengift besteht aus Eiwei\u00df, das durch die <a href=\"https:\/\/www.edogs.de\/magazin\/heisse-sommertage-mit-dem-hund\/\">Hitze<\/a> inaktiviert wird. Das Wasser sollte vorher auf der eigenen Haut ausprobiert werden, damit keine Verbrennungen durch die Hitze entstehen k\u00f6nnen.<\/li><li><strong>Menschlicher<\/strong> <strong>Speichel<\/strong> l\u00f6st ebenfalls eine Gerinnung der Proteine im Wespengift aus und verhindert starke Schwellungen bei einem Wespenstich beim Hund.\u00a0<\/li><li>Zerdr\u00fcckte Bl\u00e4tter des <strong>Spitzwegerich<\/strong> lindern den Schmerz und den Juckreiz.<div id=\"attachment_54577\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-54577\" class=\"wp-image-54577 size-full\" src=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-Hausmittel.jpg\" alt=\"Wespenstich beim Hund: Liegender Hund\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-Hausmittel.jpg 600w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-Hausmittel-300x200.jpg 300w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-Hausmittel-585x390.jpg 585w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-beim-Hund-Hausmittel-263x175.jpg 263w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-54577\" class=\"wp-caption-text\">Hausmittel verringern den Juckreiz, den Schmerz und die Schwellung an der Einstichstelle. Zur K\u00fchlung der Einstichstelle werden Eisw\u00fcrfel in ein Tuch gewickelt und auf die Schwellung gelegt. Es k\u00f6nnen auch Cool-Packs verwendet werden.<\/p><\/div><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd32449 elementor-widget elementor-widget-text-editor\" data-id=\"bd32449\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Wespenstich vorbeugen<\/h2><p>Mit dem richtigen <strong><a href=\"https:\/\/www.edogs.de\/magazin\/reizangeltraining-fuer-hunde\/\">Training<\/a><\/strong> kann der Hund abgerufen werden. Er jagt die Wespen nicht mehr. Futter und Wasser sollten im Freien immer abgedeckt werden. Bevor das Futter dem Hund gegeben wird, sollte es immer auf Wespen kontrolliert werden.\u00a0<\/p><p>Befindet sich auf dem Spazierweg ein gro\u00dfes <strong>Wespennest<\/strong>, ist es besser, einen anderen Weg einzuschlagen. So werden die Insekten nicht gereizt und f\u00fchlen sich nicht dazu verpflichtet, ihr Nest zu verteidigen.\u00a0<\/p><p>Hat der Vierbeiner bereits einmal auf einen Wespenstich beim Hund allergisch reagiert, ist bei dem Tierarzt ein <strong>Notfallset<\/strong> erh\u00e4ltlich. Dieses sollte auf Ausfl\u00fcgen immer f\u00fcr den Notfall zur Hand sein.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aaa6660 elementor-widget elementor-widget-text-editor\" data-id=\"aaa6660\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Hund hat Wespe verschluckt &#8211; und jetzt?<\/h2><p>Nach dem Verschlucken der Wespe sollten immer der<strong> Rachen und die oberen Atemwege der Hunde kontrolliert werden<\/strong>. Vielleicht ist das Insekt dort noch zu sehen. Hat die Wespe im Rachenraum oder der Speiser\u00f6hre gestochen, muss immer ein Tierarzt aufgesucht werden. Ein Wespenstich im Hals ist immer gef\u00e4hrlich, da die Atemwege zuschwellen k\u00f6nnen.\u00a0<\/p><p>Ist die Wespe in den <strong>Magen<\/strong> des Hundes gelangt, wird sie schnell durch die Magens\u00e4ure abget\u00f6tet. Meistens \u00fcberleben die Wespen den Schluckvorgang nicht. Das Gift, das sich noch in der toten Wespe befindet, kann dem Hund nicht mehr schaden. Es wird von der Salzs\u00e4ure des Magensaftes zerst\u00f6rt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cf4877 elementor-widget elementor-widget-text-editor\" data-id=\"6cf4877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Mythen und Irrt\u00fcmer \u00fcber Wespenstiche bei Hunden<\/h2><p>Es gibt viele Mythen rund um Wespenstiche, die f\u00fcr Hunde oft gef\u00e4hrlich werden k\u00f6nnen. Hier sind einige der h\u00e4ufigsten Irrt\u00fcmer:<\/p><ul><li><strong>Mythos:<\/strong> &#8222;Wespengift ist immer lebensbedrohlich.&#8220;<br \/><strong>Fakt:<\/strong> Die meisten Wespenstiche sind zwar schmerzhaft, aber selten t\u00f6dlich, au\u00dfer bei starken Allergien oder Stichen im Halsbereich.<\/li><li><strong>Mythos:<\/strong> &#8222;Hausmittel wie Essig oder Zwiebelsaft helfen gut.&#8220;<br \/><strong>Fakt:<\/strong> Diese Mittel k\u00f6nnen reizend wirken und den Zustand verschlechtern. K\u00fchlung ist die beste erste Ma\u00dfnahme.<\/li><li><strong>Mythos:<\/strong> &#8222;Wenn der Hund nicht sofort Symptome zeigt, ist alles in Ordnung.&#8220;<br \/><strong>Fakt:<\/strong> Allergische Reaktionen k\u00f6nnen zeitverz\u00f6gert auftreten. Beobachten Sie Ihren Hund mindestens 24 Stunden nach dem Stich.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-4a439bb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a439bb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-197ec93d\" data-id=\"197ec93d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-302d5d3c elementor-widget elementor-widget-html\" data-id=\"302d5d3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Wie gef\u00e4hrlich ist ein Wespenstich bei Hunden?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Normalerweise ist ein Wespenstich beim Hund nicht gef\u00e4hrlich. Die Schwellung und Schmerzen klingen schon nach kurzer Zeit ab. Zeigt der Hund eine allergische Reaktion auf das Wespengift, muss schnell erste Hilfe geleistet werden. <a href=\\\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\\\">Jetzt mehr erfahren \u25b6<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Was passiert, wenn mein Hund von einer Wespe gestochen wird?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Der Hund ist irritiert und hat Schmerzen. An der Einstichstelle entsteht eine Schwellung. Da die Wespe den Stachel wieder herauszieht, bleibt kein Fremdk\u00f6rper in der Wunde zur\u00fcck. Das Wespengift breitet sich im Gewebe aus und verursacht Juckreiz. <a href=\\\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\\\">Jetzt mehr erfahren \u25b6<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Sind Hunde immun gegen Wespenstiche?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Hunde sind nicht immun gegen Wespenstiche. Die Reaktionen auf das Wespengift fallen unterschiedlich stark aus. <a href=\\\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\\\">Jetzt mehr erfahren \u25b6<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Wie schnell kommt eine allergische Reaktion bei einem Wespenstich bei Hunden?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Eine allergische Reaktion auf einen Wespenstich beim Hund tritt innerhalb weniger Minuten nach dem Stich des Insekts auf. Die Atmung f\u00e4llt dem Hund immer schwerer. Er hechelt und wird ohne Hilfe bewusstlos. <a href=\\\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\\\">Jetzt mehr erfahren \u25b6<\/a>\"\r\n    }\r\n  }]\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Im Sommer sind auch die Wespen wieder aktiv. Spielt der Hund im Garten oder beim&hellip;<\/p>\n","protected":false},"author":68,"featured_media":54531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[368,366],"tags":[],"class_list":["post-54525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hundegesundheit","category-hundewissen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin<\/title>\n<meta name=\"description\" content=\"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren &amp; erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin\" \/>\n<meta property=\"og:description\" content=\"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren &amp; erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/\" \/>\n<meta property=\"og:site_name\" content=\"edogs\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-19T08:57:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T14:28:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michelle Breitenfeld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michelle Breitenfeld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/\"},\"author\":{\"name\":\"Michelle Breitenfeld\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/person\\\/82443777edfcc8f0a9ab4d0c809af3fc\"},\"headline\":\"Wespenstich beim Hund &#8211; Was nun zu tun ist\",\"datePublished\":\"2022-05-19T08:57:37+00:00\",\"dateModified\":\"2025-02-10T14:28:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/\"},\"wordCount\":2003,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/Wespenstich-Hund.jpg\",\"articleSection\":[\"Hundegesundheit\",\"Hundewissen von A bis Z\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/\",\"name\":\"Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/Wespenstich-Hund.jpg\",\"datePublished\":\"2022-05-19T08:57:37+00:00\",\"dateModified\":\"2025-02-10T14:28:51+00:00\",\"description\":\"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren & erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/Wespenstich-Hund.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/Wespenstich-Hund.jpg\",\"width\":780,\"height\":520,\"caption\":\"Wespenstich: Hund steht zwischen Pflanzen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wespenstich-hund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wespenstich beim Hund &#8211; Was nun zu tun ist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"name\":\"edogs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\",\"name\":\"edogs\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"edogs\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/person\\\/82443777edfcc8f0a9ab4d0c809af3fc\",\"name\":\"Michelle Breitenfeld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"caption\":\"Michelle Breitenfeld\"},\"description\":\"Michelle Breitenfeld arbeitet nach Ihrem Studium im Bereich Medienwirtschaft und Journalismus im Marketing f\u00fcr ehorses &amp; edogs. Von ihr bekommst Du die besten Tipps rund ums Thema Hund. Erreichen kannst Du Michelle unter m.breitenfeld@ehorses.de.\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/author\\\/michelle-breitenfeld\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin","description":"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren & erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/","og_locale":"de_DE","og_type":"article","og_title":"Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin","og_description":"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren & erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!","og_url":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/","og_site_name":"edogs","article_published_time":"2022-05-19T08:57:37+00:00","article_modified_time":"2025-02-10T14:28:51+00:00","og_image":[{"width":780,"height":520,"url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg","type":"image\/jpeg"}],"author":"Michelle Breitenfeld","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michelle Breitenfeld","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#article","isPartOf":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/"},"author":{"name":"Michelle Breitenfeld","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/person\/82443777edfcc8f0a9ab4d0c809af3fc"},"headline":"Wespenstich beim Hund &#8211; Was nun zu tun ist","datePublished":"2022-05-19T08:57:37+00:00","dateModified":"2025-02-10T14:28:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/"},"wordCount":2003,"commentCount":0,"publisher":{"@id":"https:\/\/www.edogs.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg","articleSection":["Hundegesundheit","Hundewissen von A bis Z"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/","url":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/","name":"Wespenstich beim Hund - Was nun zu tun ist | edogs Magazin","isPartOf":{"@id":"https:\/\/www.edogs.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#primaryimage"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg","datePublished":"2022-05-19T08:57:37+00:00","dateModified":"2025-02-10T14:28:51+00:00","description":"Wespenstich beim Hund - Anzeichen, m\u00f6gliche Gefahren & erste Hilfe Tipps \u25baJetzt mehr erfahren im edogs Magazin!","breadcrumb":{"@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#primaryimage","url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg","contentUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/Wespenstich-Hund.jpg","width":780,"height":520,"caption":"Wespenstich: Hund steht zwischen Pflanzen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.edogs.de\/magazin\/wespenstich-hund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.edogs.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Wespenstich beim Hund &#8211; Was nun zu tun ist"}]},{"@type":"WebSite","@id":"https:\/\/www.edogs.de\/magazin\/#website","url":"https:\/\/www.edogs.de\/magazin\/","name":"edogs","description":"","publisher":{"@id":"https:\/\/www.edogs.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edogs.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.edogs.de\/magazin\/#organization","name":"edogs","url":"https:\/\/www.edogs.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"edogs"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/person\/82443777edfcc8f0a9ab4d0c809af3fc","name":"Michelle Breitenfeld","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","contentUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","caption":"Michelle Breitenfeld"},"description":"Michelle Breitenfeld arbeitet nach Ihrem Studium im Bereich Medienwirtschaft und Journalismus im Marketing f\u00fcr ehorses &amp; edogs. Von ihr bekommst Du die besten Tipps rund ums Thema Hund. Erreichen kannst Du Michelle unter m.breitenfeld@ehorses.de.","url":"https:\/\/www.edogs.de\/magazin\/author\/michelle-breitenfeld\/"}]}},"_links":{"self":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts\/54525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/comments?post=54525"}],"version-history":[{"count":0,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts\/54525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media\/54531"}],"wp:attachment":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media?parent=54525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/categories?post=54525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/tags?post=54525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}