{"id":51008,"date":"2022-01-31T15:19:48","date_gmt":"2022-01-31T14:19:48","guid":{"rendered":"https:\/\/www.edogs.de\/magazin\/?p=51008"},"modified":"2022-11-14T10:15:34","modified_gmt":"2022-11-14T09:15:34","slug":"grannen-hund","status":"publish","type":"post","link":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/","title":{"rendered":"Grannen beim Hund &#8211; Die Gefahr lauert im Feld"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"51008\" class=\"elementor elementor-51008\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-d378fc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d378fc8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5c8b90\" data-id=\"a5c8b90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0164c26 elementor-widget elementor-widget-text-editor\" data-id=\"0164c26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Grannen spielen in unserem Leben nicht wirklich eine Rolle, bis ein Hund in unser Leben tritt. Vielleicht hast Du Dich bereits vor dem Einzug des Vierbeiners informiert, welche Gefahren auf Deinen Hund lauern k\u00f6nnen. Eventuell musstet ihr es aber am eigenen K\u00f6rper erleiden und habt so die gemeinen Grannen kennengelernt. Grannen beim Hund sind ein wirklich ernstes Problem. Daher besch\u00e4ftigen wir uns in diesem Artikel intensiv mit diesem Thema. Du erf\u00e4hrst, wie Du reagieren solltest, wenn Dein Hund Grannen hat, wie Du diese \u00fcberhaupt erkennst und wie Du sie entfernen und im besten Fall vermeiden kannst. Hier kannst Du auch nachlesen, warum Du die so harmlos wirkenden Grannen beim Hund auf keinen Fall untersch\u00e4tzen darfst und was sie anrichten k\u00f6nnen.\u00a0<\/strong><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-dmcheck penci-elbg-activate penci-disSticky penci-structure-20 elementor-section elementor-top-section elementor-element elementor-element-25c78b3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"25c78b3a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31188aaf\" data-id=\"31188aaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b02d1b0 elementor-widget elementor-widget-text-editor\" data-id=\"1b02d1b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #93cc5d;\">Grannen (Hund): Krankheitssteckbrief<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-181123ce elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"181123ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-temperature-high\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Symptome<\/b>: Getreideborsten im Fell des Hundes <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-chart-bar\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Verlauf<\/b>: Akut<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hospital\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Schwere der Erkrankung:<\/b>: Meist unproblematisch<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>H\u00e4ufigkeit<\/b>: Gelegentlich<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Vorkommen<\/b>: Bei allen Hunden<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-50 penci-ercol-order-2 penci-sticky-ct    elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f09787c\" data-id=\"4f09787c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d45748d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6d45748d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tint\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Diagnose<\/b>: Grannen k\u00f6nnen zu Entz\u00fcndungen und Hautirritationen f\u00fchren<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-syringe\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Behandlung<\/b>: Vorsichtiges entfernen der Grannen, ggf. Desinfizieren, im schlimmsten Fall operatives Entfernen <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-heartbeat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Prognose<\/b>: Gute Prognose<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dog\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Ansteckungsgefahr<\/b>: Nicht ansteckend<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-briefcase-medical\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Fachgebiet<\/b>: Dermatologie<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-419e5a6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"419e5a6a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a5adead\" data-id=\"2a5adead\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-642c27fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"642c27fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75fbbb1a\" data-id=\"75fbbb1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21145056 elementor-widget elementor-widget-html\" data-id=\"21145056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"FAQPage\",\r\n  \"mainEntity\": [{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Was tut man gegen Grannen beim Hund?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Wenn Du die Granne selbst aus dem Fell entfernen kannst, dann mach das rasch. Wenn sich die Granne jedoch tief im Ohr oder im Auge befinden, musst Du dies einem Tierarzt \u00fcberlassen. Befinden sich Grannen im K\u00f6rper, m\u00fcssen diese vom Tierarzt meist operativ entfernt werden. <a href=\\\"edogs.de\/magazin\/grannen-hund\/\\\"Jetzt mehr erfahren \u25ba<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Wie sch\u00fctze ich meinen Hund vor Grannen?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Vollst\u00e4ndig sch\u00fctzen kannst Du Hunde nicht. Du solltest jedoch Getreidefelder und hohe Wiesen im Hochsommer und Herbst meiden. Damit der Hund beim Spazieren nicht in das Getreidefeld sprintet, halte ihn an diesen Pl\u00e4tzen am besten an der kurzen Leine.  Gestutztes Fell kann auch hilfreich sein. Vor allem solltest Du das Fell zwischen den Zehen unter den Ballen sch\u00f6n kurz halten. <a href=\\\"edogs.de\/magazin\/grannen-hund\/\\\"Jetzt mehr erfahren \u25ba<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Sind Grannen gef\u00e4hrlich f\u00fcr Hunde?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Ja, vor allem wenn sie in die Haut eindringen. Auch im K\u00f6rper, in der Nase, im Maul und den Ohren k\u00f6nnen Grannen einen gro\u00dfen Schaden verursachen. <a href=\\\"edogs.de\/magazin\/grannen-hund\/\\\"Jetzt mehr erfahren \u25ba<\/a>\"\r\n    }\r\n  },{\r\n    \"@type\": \"Question\",\r\n    \"name\": \"Wie erkennt man Grannen beim Hund?\",\r\n    \"acceptedAnswer\": {\r\n      \"@type\": \"Answer\",\r\n      \"text\": \"Wenn sich Hunde viel kratzen, den Kopf stark sch\u00fctteln, \u00f6fter niesen, husten oder versuchen, sich etwas aus dem Fell zu bei\u00dfen, solltest Du nachsehen, was Dir der Hund sagen will. Entz\u00fcndungen, geschwollene, ger\u00f6tete oder eitrige Stellen, aber auch rote, zusammengekniffene Augen k\u00f6nnen ein Hinweis auf Grannen sein. <a href=\\\"edogs.de\/magazin\/grannen-hund\/\\\"Jetzt mehr erfahren \u25ba<\/a>\"\r\n    }\r\n  }]\r\n}\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-669bcf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"669bcf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65ae38ef\" data-id=\"65ae38ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c3059 elementor-widget elementor-widget-text-editor\" data-id=\"1c3059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Grannen beim Hund &#8211; Was ist das und warum sind sie so gef\u00e4hrlich?<\/h2><p>Bei den Grannen handelt es sich um die <strong>Getreideborsten<\/strong>, die mit einem Widerhaken versehen sind. Vor allem manche Weizensorten, Gerste und Roggen k\u00f6nnen hier sehr unangenehm werden. Du hast die Widerhaken vielleicht fr\u00fcher schon einmal bemerkt, wenn Du eine Getreide\u00e4hre angegriffen hast. \u00a0Vielleicht ist eine Granne bei einem Spaziergang im sp\u00e4ten Sommer auch schon einmal an Deiner Bekleidung h\u00e4ngen geblieben. Die hast Du einfach abgezupft. Eventuell hat es Dich kurz in den Fingern geritzt oder gestochen. F\u00fcr Menschen haben Grannen in der Regel aber keine negativen Auswirkungen. Ganz anders aber sieht es bei Hunden aus.<\/p><p>Grannen sind eine <strong>biologische Notwendigkeit<\/strong>. Jede Pflanze muss eine M\u00f6glichkeit haben, sich zu vermehren. Das Getreide vermehrt sich \u00fcber die Grannen, da an ihnen die Samen angeh\u00e4ngt sind. Sie heften sich an einem Tr\u00e4ger fest und fallen an einem anderen Ort wieder ab. Dies ist der nat\u00fcrliche Weg der Vermehrung von Getreide. Dadurch geht die Gefahr von Grannen meist erst im<strong> Sp\u00e4tsommer und im Herbst<\/strong> aus. Zu dieser Zeit wird das Getreide reif. Die \u00c4hren leuchten golden, wenn es Zeit f\u00fcr die Ernte ist. Das Getreide ist nun auch sehr trocken und die Spitzen brechen rasch ab. So k\u00f6nnen sich die Grannen schnell an alles anheften, was des Weges kommt. In den meisten F\u00e4llen sind es Tiere, unter anderem auch unsere Hunde.<\/p><div id=\"attachment_51012\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-51012\" class=\"wp-image-51012 size-full\" src=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-feld-von-unten.jpg\" alt=\"Grannen Hund: Hund auf Feld\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-feld-von-unten.jpg 600w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-feld-von-unten-300x200.jpg 300w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-feld-von-unten-585x390.jpg 585w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-feld-von-unten-263x175.jpg 263w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-51012\" class=\"wp-caption-text\">Grannen gelangen durch das Sch\u00fctteln des Hundes oftmals noch tiefer ins Fell.<\/p><\/div><p>Grannen <strong>k\u00f6nnen richtig gef\u00e4hrlich werden, wenn sie nicht entfernt werden<\/strong>. Durch die Widerhaken lassen sie sich nicht einfach von den Vierbeinern absch\u00fctteln. Sie dringen durchs Sch\u00fctteln meist noch tiefer ins Fell ein und k\u00f6nnen auf die Haut sto\u00dfen. Dort sind sie nicht nur schmerzhaft, sondern k\u00f6nnen auch Entz\u00fcndungen verursachen. Setzt sich die Granne an den <strong>Pfoten <\/strong>zwischen den Zehen fest, so kann sie dort auch riesigen Schaden verursachen. Die Pfote entz\u00fcndet sich und h\u00e4ufig muss die Granne vom Tierarzt herausgeschnitten werden.<\/p><p>Versucht der Hund die Granne mit dem <strong>Maul oder der Nase <\/strong>aus dem Fell zu entfernen, kann sich diese im Maul festsetzen und dort f\u00fcr Entz\u00fcndungen sorgen. Der Hund kann die Grannen auch einatmen und diese gelangen so in die <strong>Lungen<\/strong>. \u00dcber den K\u00f6rper k\u00f6nnen die widerlichen \u00c4hrenspitzen auch an andere Organe gelangen. Dort sorgen sie f\u00fcr m\u00e4chtig \u00c4rger, Schmerzen und im schlimmsten Fall kann der Hund daran sogar sterben. Grannen im Auge k\u00f6nnen schmerzhafte Bindehautentz\u00fcndungen verursachen. Nicht erkannt kann der Hund dadurch sogar blind werden. Gelangen Grannen ins <strong>Ohr<\/strong>, k\u00f6nnten sie dort das Trommelfell verletzen und der Hund bekommt Probleme mit dem H\u00f6ren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d97395f elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6d97395f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSind Grannen gef\u00e4hrlich f\u00fcr Hunde?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJa, vor allem wenn sie in die Haut eindringen. Auch im K\u00f6rper, in der Nase, im Maul und den Ohren k\u00f6nnen Grannen einen gro\u00dfen Schaden verursachen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b12e0cb elementor-widget elementor-widget-text-editor\" data-id=\"b12e0cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Hund hat Grannen &#8211; Typische Symptome im \u00dcberblick<\/h2><p>Wenn die Grannen frisch im Fell h\u00e4ngen bleiben, kannst Du sie gut sehen und am besten gleich entfernen. Der Hund wird Dir auch anzeigen, dass sich ein unangenehmer Fremdk\u00f6rper an seinem K\u00f6rper befindet. Der <strong>Vierbeiner sch\u00fcttelt und <a href=\"https:\/\/www.edogs.de\/magazin\/juckreiz-beim-hund\/\">kratzt sich<\/a>, leckt und nibbelt sich die Pfote bzw. die Pfoten<\/strong> und hustet oder <a href=\"https:\/\/www.edogs.de\/magazin\/schnupfen-beim-hund\/\">niest<\/a>, wenn er die Grannen in die Nase oder ins Maul bekommen hat.\u00a0<\/p><p>Typische Symptome sind auch <strong>ger\u00f6tete und zugekniffene Augen, entz\u00fcndete Stellen auf der Haut, rote Ohren, vermehrtes Kopfsch\u00fctteln und Schwellungen<\/strong>. Auch wenn Dein<a href=\"https:\/\/www.edogs.de\/magazin\/hund-humpelt-stumpfes-trauma-behandeln\/\"> Hund humpelt<\/a>, solltest Du kontrollieren, ob in den Pfoten eventuell eine Granne steckt.<\/p><h2>Wo setzen sich Grannen am h\u00e4ufigsten fest?<\/h2><p>Grannen sind nicht w\u00e4hlerisch, das Getreide will sich einfach vermehren. Grannen <strong>bleiben am Fell h\u00e4ngen und heften sich am Kopf fest<\/strong>. Dort k\u00f6nnen sie schnell eingeatmet oder geschluckt werden, oder sich im Geh\u00f6rgang verkriechen. Gerne verstecken sich Grannen zwischen den Zehen, in den Achselh\u00f6hlen des Hundes, im Genitalbereich, hinter den Ohren, an den Augen in Hautfalten oder in der Rute.\u00a0<\/p><p>Besonders gef\u00e4hrlich ist es jedoch, wenn sich die Grannen in den<strong> inneren Organen<\/strong> festsetzen. In der Lunge und anderen Organen zum Beispiel k\u00f6nnte die Granne sogar austreiben. So wird ein Teil dieses Organs zerst\u00f6rt. Wenn Du Gl\u00fcck hast, kann in diesem Fall ein Teil der Lunge entfernt werden. Diese kann sich wieder regenerieren. Bei anderen Organen sieht es schlechter aus. Hier k\u00f6nnen Grannen tats\u00e4chlich bis zum Tod f\u00fchren. Daher ist es wichtig, dass Du Deinen Vierbeiner nach dem <a href=\"https:\/\/www.edogs.de\/magazin\/gassi-gehen\/\">Spazieren<\/a> immer genau kontrollierst. Schau genau an diesen markanten Stellen nach. So k\u00f6nntest Du gleichzeitig auch andere Parasiten wie <a href=\"https:\/\/www.edogs.de\/magazin\/sommerzeit-ist-zeckenzeit-wie-du-zecken-beim-hund-vermeidest\/\">Zecken<\/a> entdecken.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a061a28 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a061a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie erkennt man Grannen beim Hund?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWenn sich Hunde viel kratzen, den Kopf stark sch\u00fctteln, \u00f6fter niesen, <a href=\"https:\/\/www.edogs.de\/magazin\/husten-hund\/\">husten<\/a> oder versuchen, sich etwas aus dem Fell zu bei\u00dfen, solltest Du nachsehen, was Dir der Hund sagen will. Entz\u00fcndungen, geschwollene, ger\u00f6tete oder eitrige Stellen, aber auch rote, zusammengekniffene Augen k\u00f6nnen ein Hinweis auf Grannen sein.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26a3481 elementor-widget elementor-widget-text-editor\" data-id=\"26a3481\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Mein Hund hat Grannen &#8211; Was tun?<\/h2><p>Befinden sich die Grannen im Fell, kannst Du diese <strong>einfach selbst entfernen<\/strong>. Nimm dazu Deine Finger oder eine Pinzette zur Hilfe. Mit der Pinzette musst du jedoch aufpassen, damit die spr\u00f6den Grannen nicht abbrechen. Es k\u00f6nnten kleine Teile der Widerhaken im Fell verbleiben, auf die Haut <a href=\"https:\/\/www.edogs.de\/magazin\/wandern-mit-hund\/\">wandern<\/a> und dort Ekzeme oder Fisteln verursachen.<\/p><p>Wenn Du eine Granne am Ohr oder am Auge entdeckst, musst Du besonders vorsichtig sein. Wenn es wirklich einfach geht, kannst Du sie selbst entfernen. Passe aber auf, dass nicht beispielsweise ein kleiner Teil in den Geh\u00f6rgang eindringt. Wenn Du bef\u00fcrchtest, dass Dein Hund Grannen eingeatmet oder verschluckt hat, sollte der schnellste Weg zum <strong>Tierarzt <\/strong>f\u00fchren.\u00a0<\/p><div id=\"attachment_51011\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-51011\" class=\"wp-image-51011 size-full\" src=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-rennt-blumenwiese.jpg\" alt=\"Grannen Hund: Hund rennt auf Blumenwiese\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-rennt-blumenwiese.jpg 600w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-rennt-blumenwiese-300x200.jpg 300w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-rennt-blumenwiese-585x390.jpg 585w, https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-hund-rennt-blumenwiese-263x175.jpg 263w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><p id=\"caption-attachment-51011\" class=\"wp-caption-text\">Befinden sich die Grannen im Fell, kannst Du diese einfach selbst entfernen.<\/p><\/div><h2>Diagnose und Nachweis vom Grannen bei Hunden<\/h2><p>Wurden die Grannen nicht sofort entdeckt, so ist vielleicht bereits eine <strong>Entz\u00fcndung <\/strong>entstanden. Eitrige, geschwollene oder stark ger\u00f6tete Pusteln auf der Haut k\u00f6nnen darauf hinweisen. Wenn Dein Hund st\u00e4ndig niest, solltest Du den Tierarzt darauf hinweisen, dass Du Grannen bef\u00fcrchtest. So leuchtet er ganz genau in die Nase, kontrolliert das Maul und den Rachen und auch die Ohren.<\/p><p>Auch mittels <strong>Ultraschall und <a href=\"https:\/\/www.edogs.de\/magazin\/hund-roentgen\/\">R\u00f6ntgen<\/a><\/strong> k\u00f6nnen Grannen lokalisiert werden. Sobald die Granne gefunden ist, ist der erste Schritt getan. Nun muss sie entfernt werden. Meist geht dies nur mehr operativ. Das Gewebe muss entfernt werden, auch wenn sich die Granne in einem Organ festgesetzt hat. Weiter muss der Hund <strong>Antibiotikum <\/strong>gegen die Entz\u00fcndung einnehmen. Auch gegen die Schmerzen verschreibt der Tierarzt deinem Vierbeiner Medikamente.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fada63 elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6fada63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWas tut man gegen Grannen beim Hund?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWenn Du die Granne selbst aus dem Fell entfernen kannst, dann mach das rasch. Wenn sich die Granne jedoch tief im Ohr oder im Auge befinden, musst Du dies einem Tierarzt \u00fcberlassen. Befinden sich Grannen im K\u00f6rper, m\u00fcssen diese vom Tierarzt meist operativ entfernt werden.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4108bfc elementor-widget elementor-widget-text-editor\" data-id=\"4108bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Prophylaxe und Vorbeugung &#8211; Wie sieht ein Grannenschutz f\u00fcr Hund aus?<\/h2><p>Zu 100 Prozent kannst Du Deinen Hund nicht vor Grannen sch\u00fctzen. Die einzige M\u00f6glichkeit w\u00e4re, das Haus nicht mehr zu verlassen. Dies ist f\u00fcr einen Hund jedoch ein Ding der Unm\u00f6glichkeit. Machst Du einen Spaziergang oder gehst mit Deinem Hund wandern, solltest ab Sommer auf jeden Fall <strong>Getreidefelder meiden<\/strong>. So wird das Risiko etwas vermindert. Da sich Getreide aber sehr effektiv vermehrt, w\u00e4chst es auch spontan in Wiesen, Gr\u00fcnstreifen und kann sogar in der Stadt in einem Park oder einer kleinen Gr\u00fcnfl\u00e4che zu finden sein. Im <strong>eigenen<\/strong> <strong>Garten <\/strong>solltest Du auch regelm\u00e4\u00dfig \u00fcberpr\u00fcfen, ob sich dort Getreide oder potentiell gef\u00e4hrliches Unkraut anges\u00e4t hat. Entferne es sofort.<\/p><p>Lasse Deinen Hund bei drohender Grannen-Gefahr nur an der<strong> kurzen Leine<\/strong> laufen. Lasse ihn niemals in Getreidefelder laufen und gib auch bei Wiesen mit sehr hohem Gras acht. Vor allem aber schau Dir im Internet <strong>Bilder von Grannen <\/strong>an, damit Du alle sofort erkennen kannst.<\/p><p><strong>K\u00e4mme und b\u00fcrste den Hund regelm\u00e4\u00dfig <\/strong>und sofort nach dem Spaziergang. Eventuell kannst Du das Fell auch trimmen oder scheren. Vergiss bei der <strong>Kontrolle <\/strong>die Zwischenr\u00e4ume der Zehen des Hundes nicht, schau in die Hautfalten, die Achseln, in und hinter die Ohren und taste auch den Schwanz gut ab.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4feaadf elementor-view-stacked elementor-position-inline-start elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4feaadf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie sch\u00fctze ich meinen Hund vor Grannen?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVollst\u00e4ndig sch\u00fctzen kannst Du Hunde nicht. Du solltest jedoch Getreidefelder und hohe Wiesen im Hochsommer und Herbst meiden. Damit der Hund beim <a href=\"https:\/\/www.edogs.de\/magazin\/wie-oft-muss-ein-hund-raus\/\">Spazieren<\/a> nicht in das Getreidefeld sprintet, halte ihn an diesen Pl\u00e4tzen am besten an der kurzen Leine.  Gestutztes Fell kann auch hilfreich sein. Vor allem solltest Du das Fell zwischen den Zehen unter den Ballen sch\u00f6n kurz halten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Grannen spielen in unserem Leben nicht wirklich eine Rolle, bis ein Hund in unser Leben&hellip;<\/p>\n","protected":false},"author":68,"featured_media":51009,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[368,366],"tags":[],"class_list":["post-51008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hundegesundheit","category-hundewissen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grannen beim Hund | edogs Magazin<\/title>\n<meta name=\"description\" content=\"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edogs.de\/magazin\/grannen-hund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grannen beim Hund | edogs Magazin\" \/>\n<meta property=\"og:description\" content=\"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edogs.de\/magazin\/grannen-hund\/\" \/>\n<meta property=\"og:site_name\" content=\"edogs\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T14:19:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-14T09:15:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michelle Breitenfeld\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michelle Breitenfeld\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/\"},\"author\":{\"name\":\"Michelle Breitenfeld\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/person\\\/82443777edfcc8f0a9ab4d0c809af3fc\"},\"headline\":\"Grannen beim Hund &#8211; Die Gefahr lauert im Feld\",\"datePublished\":\"2022-01-31T14:19:48+00:00\",\"dateModified\":\"2022-11-14T09:15:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/\"},\"wordCount\":1686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/grannen-beim-hund.jpg\",\"articleSection\":[\"Hundegesundheit\",\"Hundewissen von A bis Z\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/\",\"name\":\"Grannen beim Hund | edogs Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/grannen-beim-hund.jpg\",\"datePublished\":\"2022-01-31T14:19:48+00:00\",\"dateModified\":\"2022-11-14T09:15:34+00:00\",\"description\":\"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/grannen-beim-hund.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/grannen-beim-hund.jpg\",\"width\":780,\"height\":520,\"caption\":\"grannen-hund\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/grannen-hund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grannen beim Hund &#8211; Die Gefahr lauert im Feld\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"name\":\"edogs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\",\"name\":\"edogs\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"edogs\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/person\\\/82443777edfcc8f0a9ab4d0c809af3fc\",\"name\":\"Michelle Breitenfeld\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/michelle-breitenfeld-edogs-autor-96x96.jpg\",\"caption\":\"Michelle Breitenfeld\"},\"description\":\"Michelle Breitenfeld arbeitet nach Ihrem Studium im Bereich Medienwirtschaft und Journalismus im Marketing f\u00fcr ehorses &amp; edogs. Von ihr bekommst Du die besten Tipps rund ums Thema Hund. Erreichen kannst Du Michelle unter m.breitenfeld@ehorses.de.\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/author\\\/michelle-breitenfeld\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grannen beim Hund | edogs Magazin","description":"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/","og_locale":"de_DE","og_type":"article","og_title":"Grannen beim Hund | edogs Magazin","og_description":"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!","og_url":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/","og_site_name":"edogs","article_published_time":"2022-01-31T14:19:48+00:00","article_modified_time":"2022-11-14T09:15:34+00:00","og_image":[{"width":780,"height":520,"url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg","type":"image\/jpeg"}],"author":"Michelle Breitenfeld","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Michelle Breitenfeld","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#article","isPartOf":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/"},"author":{"name":"Michelle Breitenfeld","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/person\/82443777edfcc8f0a9ab4d0c809af3fc"},"headline":"Grannen beim Hund &#8211; Die Gefahr lauert im Feld","datePublished":"2022-01-31T14:19:48+00:00","dateModified":"2022-11-14T09:15:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/"},"wordCount":1686,"commentCount":0,"publisher":{"@id":"https:\/\/www.edogs.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg","articleSection":["Hundegesundheit","Hundewissen von A bis Z"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.edogs.de\/magazin\/grannen-hund\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/","url":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/","name":"Grannen beim Hund | edogs Magazin","isPartOf":{"@id":"https:\/\/www.edogs.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#primaryimage"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg","datePublished":"2022-01-31T14:19:48+00:00","dateModified":"2022-11-14T09:15:34+00:00","description":"Grannen beim Hund - Warum sie so gef\u00e4hrlich sind und was Du dagegen tun kannst \u25ba Jetzt mehr erfahren im edogs Magazin!","breadcrumb":{"@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edogs.de\/magazin\/grannen-hund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#primaryimage","url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg","contentUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/grannen-beim-hund.jpg","width":780,"height":520,"caption":"grannen-hund"},{"@type":"BreadcrumbList","@id":"https:\/\/www.edogs.de\/magazin\/grannen-hund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.edogs.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Grannen beim Hund &#8211; Die Gefahr lauert im Feld"}]},{"@type":"WebSite","@id":"https:\/\/www.edogs.de\/magazin\/#website","url":"https:\/\/www.edogs.de\/magazin\/","name":"edogs","description":"","publisher":{"@id":"https:\/\/www.edogs.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edogs.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.edogs.de\/magazin\/#organization","name":"edogs","url":"https:\/\/www.edogs.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"edogs"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/person\/82443777edfcc8f0a9ab4d0c809af3fc","name":"Michelle Breitenfeld","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","contentUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/michelle-breitenfeld-edogs-autor-96x96.jpg","caption":"Michelle Breitenfeld"},"description":"Michelle Breitenfeld arbeitet nach Ihrem Studium im Bereich Medienwirtschaft und Journalismus im Marketing f\u00fcr ehorses &amp; edogs. Von ihr bekommst Du die besten Tipps rund ums Thema Hund. Erreichen kannst Du Michelle unter m.breitenfeld@ehorses.de.","url":"https:\/\/www.edogs.de\/magazin\/author\/michelle-breitenfeld\/"}]}},"_links":{"self":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts\/51008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/comments?post=51008"}],"version-history":[{"count":0,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/posts\/51008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media\/51009"}],"wp:attachment":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media?parent=51008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/categories?post=51008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/tags?post=51008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}