{"id":13844,"date":"2017-11-06T16:10:50","date_gmt":"2017-11-06T15:10:50","guid":{"rendered":"https:\/\/magazin.edogs.de\/?post_type=hunderasse&#038;p=13844"},"modified":"2025-04-30T11:32:22","modified_gmt":"2025-04-30T09:32:22","slug":"hollandse-smoushond","status":"publish","type":"hunderassen","link":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/","title":{"rendered":"Hollandse Smoushond"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13844\" class=\"elementor elementor-13844\" data-elementor-post-type=\"hunderassen\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-7298980e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7298980e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2649bcd9\" data-id=\"2649bcd9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c8ab303 elementor-widget elementor-widget-text-editor\" data-id=\"4c8ab303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Der Hollandse Smoushond ist eine aus den Niederlanden stammende Hunderasse. Sie ist durch die FCI offiziell anerkannt und wird der FCI-Gruppe 2, der Gruppe der Pinscher und Schnauzer &#8211; Molossoide &#8211; Schweizer Sennenhunde, und der Sektion 1.3, der Sektion des Smoushond, zugeordnet. Im Verzeichnis der FCI ist der holl\u00e4ndische Hund unter der Standardnummer 308 zu finden. Er gilt nicht als Arbeitsgebrauchshund, eigentlich sich hingegen gut als Familien- und Begleithund. Au\u00dferdem ist die freundliche Rasse auf der Liste der Haushunde zu finden.<\/strong> \n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-21 elementor-section elementor-top-section elementor-element elementor-element-7d39dec elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7d39dec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-33 penci-ercol-order-1 penci-sticky-sb penci-sidebarSC   elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1ba79173\" data-id=\"1ba79173\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d5f8fe3 elementor-widget elementor-widget-text-editor\" data-id=\"5d5f8fe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Hollandse Smoushond im Steckbrief<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a45bd83 elementor-widget elementor-widget-text-editor\" data-id=\"a45bd83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pcrstb-wrap\"><table class=\"edogsRasseSteckbrief\">\n<tbody>\n<tr>\n<th colspan=\"2\">Steckbrief<\/th>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Gr\u00f6\u00dfe:<\/td>\n<td>36-42 cm<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Gewicht:<\/td>\n<td>09.10.2017 kg<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">FCI-Gruppe:<\/td>\n<td>2: Pinscher und Schnauzer &#8211; <a href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/alano-espanol\/\">Molosser<\/a> &#8211; Schweizer Sennenhunde und andere Rassen<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Sektion:<\/td>\n<td>1.3: Pinscher und Schnauzer, Smoushond<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Herkunftsland:<\/td>\n<td>Niederlande<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Farben:<\/td>\n<td>Senf-Gelb<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Lebenserwartung:<\/td>\n<td>12-14 Jahre<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Geeignet als:<\/td>\n<td><a href=\"https:\/\/www.edogs.de\/magazin\/familienhund\/\">Familienhund<\/a><\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Sportarten:<\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Charakter:<\/td>\n<td>Anh\u00e4nglich, Lebendig, Akitv, Wachsam, Geduldig, Fr\u00f6hlich, Robust, Freundlich<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Auslaufbed\u00fcrfnisse:<\/td>\n<td>hoch<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Sabber-Potential:<\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">St\u00e4rke des Haarens:<\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Pflegeaufwand:<\/td>\n<td>mittel<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Fellstruktur:<\/td>\n<td>rauh, drahtig, hart, gerade<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Kinderfreundlich:<\/td>\n<td>ja<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Familienhund:<\/td>\n<td>ja<\/td>\n<\/tr>\n<tr>\n<td class=\"rowHead\">Sozial:<\/td>\n<td>&#8211;<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"penci-ercol-66 penci-ercol-order-2 penci-sticky-ct    elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-45b1e646\" data-id=\"45b1e646\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63d36a3d elementor-widget elementor-widget-text-editor\" data-id=\"63d36a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Herkunft und Rassegeschichte<\/h2><p>Der Hollandse Smoushound wird auch gerne als <strong>Holl\u00e4ndischer Rattler<\/strong> bezeichnet, was auf seine fr\u00fchere Funktion als <strong>Rattenf\u00e4nger<\/strong> zur\u00fcckzuf\u00fchren ist. Die <a href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/mittelgrosse-hunde\/\">mittelgro\u00dfen Hunde<\/a> wurden dazu verwendet, die St\u00e4lle und H\u00f6fe von Ratten, M\u00e4usen und anderen Kleintieren zu befreien. Rattler bedeutet soviel wie Ratten- oder M\u00e4usef\u00e4nger. Der Hollandse Smoushond wurde nicht gezielt gez\u00fcchtet, sondern er entwickelte sich durch seinen Gebrauch als <strong>Jagd- und Begleithund<\/strong>. Das Aussehen der Hunde stand aus diesem Grund nie im Fokus, weshalb der Holl\u00e4nder quadratisch gebaut ist und sein Fell struppig und wetterfest ist. Die freundlichen Hunde sollten darauf ausgelegt sein, bei jedem Wetter auf Rattenjagd zu gehen und ihre Besitzer auf jeder Reise zu begleiten.<\/p><p>Erst am <strong>Anfang des 20. Jahrhundert begann die selektierte Zucht<\/strong> der niederl\u00e4ndischen Rasse. 1905 wurde ein eigener Club, der Hollands Smoushond Club, gegr\u00fcndet, um die Rasse vor dem Aussterben zu bewahren. In der folgenden Zucht wurde das zuvor nicht beachtete Aussehen des Hundes immer mehr in den Vordergrund gestellt. Der struppige Kopf des Holl\u00e4nders wurde zum Merkmal der Rasse und war ausschlaggebend f\u00fcr die Bezeichnung Smoushond.<\/p><p>Wie viele andere Hunderassen, war auch der Hollandse Smoushond durch den Ersten und Zweiten Weltkrieg betroffen. Besonders nach dem Zweiten Weltkrieg war das \u00dcberleben der Rasse ungekl\u00e4rt, doch 1972 fing eine Dame namens Bartmann mit der <strong>R\u00fcckz\u00fcchtung der niederl\u00e4ndischen Hunde<\/strong> an. Schnell zeigten sich erste Erfolge und das \u00dcberleben der Rasse war gesichert. Sp\u00e4ter wurde in die Zucht die <a href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/border-terrier\/\">Border Terrier<\/a> Zucht mit einbezogen, was unter anderem f\u00fcr den Erhalt des Hollandse Smoushond sorgte.<\/p><p>Die aus den Niederlanden stammende Hunderasse wurde<strong> von der FCI 1981 offiziell anerkannt.<\/strong> Der letztg\u00fcltige Standard wurde im Februar 2010 verfasst und schlie\u00dflich zwei Jahre sp\u00e4ter darauf publiziert. 1977 wurde der Hollandse Smoushond vom Raad van Beheer, dem nationalen kinologischen Dachverband in den Niederlanden, anerkannt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7c39e9 elementor-widget elementor-widget-text-editor\" data-id=\"6d7c39e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Wesen &amp; Charakter vom Hollandse Smoushond<\/h2><p>Die strubbelige Hunderasse strahlt f\u00f6rmlich vor Lebensfreude und Lebhaftigkeit. Die Hunde sind \u00fcberaus freundlich und aktiv. Der Hollandse Smoushond zaubert durch seine <strong>positive Art<\/strong> und sein sonniges Gem\u00fct jedem ein L\u00e4cheln ins Gesicht. Die Fr\u00f6hlichkeit und Verspieltheit des Hollands Smoushond macht ihn auch f\u00fcr Kinder zu einem <strong>treuen Spielgef\u00e4hrten<\/strong>. Angst, Aggression oder Nervosit\u00e4t liegen dem Holl\u00e4nder fern. Er ist ein sehr <strong><a href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/anhaengliche-hunderassen\/\">anh\u00e4nglicher Hund<\/a><\/strong> und <strong>anschmiegsamer Weggef\u00e4hrte<\/strong>, der gerne Abenteuer erlebt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-32557621 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32557621\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a2851b0\" data-id=\"4a2851b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-460702c elementor-widget elementor-widget-text-editor\" data-id=\"460702c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Auf Spazierg\u00e4ngen kann er<strong> problemlos von der Leine gelassen<\/strong> werden und wird nicht weglaufen. Der Hollandse Smoushond besitzt keinen ausgepr\u00e4gten Jagdtrieb und ist sehr <strong>auf sein Rudel fixiert<\/strong>. Die niederl\u00e4ndische Rasse ist sehr sozial und ihr Fokus liegt auf ihrem Rudel. Zwar ist der Hollandse Smoushond durchaus bereit seine Familie bei Gefahr zu verteidigen und zeigt auch<strong> Schutz- und Wachverhalten,<\/strong> doch diese Triebe sind nicht stark ausgepr\u00e4gt.<\/p><p>Der Holl\u00e4nder ist <strong>keinesfalls ein Kl\u00e4ffer und <\/strong><strong>gut mit anderen Haustieren vertr\u00e4glich<\/strong>. Er bewegt sich gerne und begleitet seinen Menschen gerne \u00fcberall hin. Die Rasse gilt als sehr anschmiegsam, freundlich und neugierig. Der Hollandse Smoushond ist ein echter Allrounder der sich problemlos vielen Situationen anpassen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-693375f4 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"693375f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 40 40\"><defs><style>      .cls-1 {        fill: #73b99b;        stroke-width: 0px;      }    <\/style><\/defs><path class=\"cls-1\" d=\"M20.1,28.6c.5,0,.9-.2,1.2-.5.3-.3.5-.7.5-1.2v-6.9c0-.5-.2-.9-.5-1.2-.3-.3-.7-.5-1.2-.5s-.9.2-1.2.5c-.3.3-.5.7-.5,1.2v6.9c0,.5.2.9.5,1.2.3.4.7.5,1.2.5ZM20,15.6c.5,0,1-.2,1.3-.5.4-.4.5-.8.5-1.3s-.2-1-.5-1.4c-.3-.4-.8-.6-1.3-.6s-1,.2-1.3.5c-.4.4-.5.8-.5,1.3s.2,1,.5,1.3c.3.5.8.7,1.3.7ZM20,37.3c-2.4,0-4.7-.5-6.8-1.4-2.1-.9-3.9-2.1-5.5-3.7-1.6-1.6-2.8-3.4-3.7-5.5s-1.4-4.4-1.4-6.8.5-4.7,1.4-6.8c.9-2.1,2.1-3.9,3.7-5.5s3.4-2.8,5.5-3.7,4.4-1.4,6.8-1.4,4.7.5,6.8,1.4c2.1.9,3.9,2.1,5.5,3.7,1.6,1.6,2.8,3.4,3.7,5.5s1.4,4.4,1.4,6.8-.5,4.7-1.4,6.8c-.9,2.1-2.1,3.9-3.7,5.5s-3.4,2.8-5.5,3.7c-2.1,1-4.4,1.4-6.8,1.4Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie gro\u00df wird ein Hollandse Smoushond?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin Hollandse Smoushond erreicht ein Stockma\u00df zwischen 35 und 42 cm, je nach Geschlecht des Hundes. R\u00fcden sind meist etwa 2-7 cm gr\u00f6\u00dfer als H\u00fcndinnen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60eb3241 elementor-widget elementor-widget-text-editor\" data-id=\"60eb3241\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Aussehen des Hollandse Smoushond<\/h2><p>Das Aussehen der niederl\u00e4ndischen Hunderasse wird dominiert durch das rassentypische <strong>strubbelige Fell<\/strong> und den <strong>quadratischen K\u00f6rperbau<\/strong>. Der K\u00f6rper des Hollande Smoushond ist kompakt, ohne schwer zu wirken. Die Form ist quadratisch und kr\u00e4ftig, doch zugleich sportlich ohne derb zu wirken. Die Hunde werden <strong>maximal 42 cm hoch<\/strong> und erreichen ein Gewicht zwischen <strong>9 bis 10 kg<\/strong>. H\u00fcndinnen besitzen ein Stockma\u00df zwischen 35 und 40 cm, w\u00e4hrend R\u00fcden eine Widerristh\u00f6he von 37 bis 42 cm erreichen. Die L\u00e4ufe sind schlank und lang.<\/p><p>Das <strong>Haarkleid ist drahtig, rau und von harter Struktur<\/strong>. Es steht gerade vom K\u00f6rper ab, was dem Hollandse Smoushond seinen charakteristischen Strubbellook verleiht. Es ist etwa vier bis sieben cm lang und kann in einfarbig gelb sowie allen daraus resultierenden Schattierungen auftreten. Meist sind die niederl\u00e4ndischen Hunde in einem <strong>dunkeln Strohgelb<\/strong> gef\u00e4rbt. Der Kinn- und Backenbart sowie die Ohren und Augenbrauen sind meist etwas dunkler als der Rest des K\u00f6rpers. Die Ohren des Hollandse Smoushond sind proportional zum Rest des Hundes eher klein und fallen flach an den Wangen liegend nach vorne ab. Sie sind dreieckig, doch die Ecken sind leicht abgerundet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-191c3b6 elementor-widget elementor-widget-text-editor\" data-id=\"191c3b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Erziehung &amp; Haltung des Hollandse Smoushonds &#8211; Das gilt es zu beachten<\/h2><p>Der Hollandse Smoushond ist <strong>m\u00e4\u00dfig gut trainierbar<\/strong>. Er besitzt durchaus seinen eigenen Willen, doch findet Freude am <a href=\"https:\/\/www.edogs.de\/magazin\/reizangeltraining-fuer-hunde\/\">Training<\/a> mit seinem Besitzer. Es ist wichtig, dass die Bindung zwischen Halter und Hund bereits im Welpenalter gest\u00e4rkt wird, um ein harmonisches Zusammenleben zu garantieren. Der Hollandse Smoushond besitzt ein best\u00e4ndiges Temperament und ein ausgeglichenes Wesen. Er ist leicht zu begeistern und findet <strong>Freude am Kontakt mit seiner Familie<\/strong>. Bei der Erziehung des Niederl\u00e4nders ist es besonders wichtig, dass dem Hund <strong>von Beginn an klare Regeln<\/strong> vermittelt werden. Die Hunde neigen zu unabh\u00e4ngigem Verhalten und l\u00f6sen Probleme mit hoher Eigenst\u00e4ndigkeit. Aus diesem Grund sollten klare Regeln in der Erziehung herrschen und ein konsequentes und f\u00fchrungsstarkes Auftreten des Besitzers ist von Vorteil.<br \/>Die Haltung des Hollands Smoushond gestaltet sich <strong>relativ entspannt<\/strong>. Die Hunde besitzen als fr\u00fcherer Jagdhunde einen hohen Bewegungsdrang, weshalb sie regelm\u00e4\u00dfig zu langen Spazierg\u00e4ngen ausgef\u00fchrt werden sollten. Aufgrund seiner Gr\u00f6\u00dfe kann der Holl\u00e4nder sowohl in einer Wohnung als auch in einem Haus mit Auslaufm\u00f6glichkeit gehalten werden. Bei der Haltung des Jagdhundes ist vor allem auf <strong>ausreichend Auslastung<\/strong> des Hundes zu achten, sowohl geistig als auch k\u00f6rperlich. Der Hollandse Smoushond ist durchaus kinderfreundlich, weshalb er sich sowohl als <a href=\"https:\/\/www.edogs.de\/magazin\/familienhund\/\">Familienhund<\/a>, als auch als Begleithund eignet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdce864 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"fdce864\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 40 40\"><defs><style>      .cls-1 {        fill: #73b99b;        stroke-width: 0px;      }    <\/style><\/defs><path class=\"cls-1\" d=\"M20.1,28.6c.5,0,.9-.2,1.2-.5.3-.3.5-.7.5-1.2v-6.9c0-.5-.2-.9-.5-1.2-.3-.3-.7-.5-1.2-.5s-.9.2-1.2.5c-.3.3-.5.7-.5,1.2v6.9c0,.5.2.9.5,1.2.3.4.7.5,1.2.5ZM20,15.6c.5,0,1-.2,1.3-.5.4-.4.5-.8.5-1.3s-.2-1-.5-1.4c-.3-.4-.8-.6-1.3-.6s-1,.2-1.3.5c-.4.4-.5.8-.5,1.3s.2,1,.5,1.3c.3.5.8.7,1.3.7ZM20,37.3c-2.4,0-4.7-.5-6.8-1.4-2.1-.9-3.9-2.1-5.5-3.7-1.6-1.6-2.8-3.4-3.7-5.5s-1.4-4.4-1.4-6.8.5-4.7,1.4-6.8c.9-2.1,2.1-3.9,3.7-5.5s3.4-2.8,5.5-3.7,4.4-1.4,6.8-1.4,4.7.5,6.8,1.4c2.1.9,3.9,2.1,5.5,3.7,1.6,1.6,2.8,3.4,3.7,5.5s1.4,4.4,1.4,6.8-.5,4.7-1.4,6.8c-.9,2.1-2.1,3.9-3.7,5.5s-3.4,2.8-5.5,3.7c-2.1,1-4.4,1.4-6.8,1.4Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIst der Hollandse Smoushond ein Familienhund?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tJa, der Hollandse Smoushond eignet sich sehr gut als Familienhund. Er ist sehr verspielt, anh\u00e4nglich und geht liebevoll mit Kindern um.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79d37eee elementor-widget elementor-widget-text-editor\" data-id=\"79d37eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Ern\u00e4hrung des Hollandse Smoushonds<\/h2><p>Die Ern\u00e4hrung des Hollandse Smoushond ist <strong>sehr unkompliziert<\/strong>. Die freundlichen Hunde weisen meist <strong>keine Futtermittel-Unvertr\u00e4glichkeiten<\/strong> auf oder leiden an Krankheiten, welche die Ern\u00e4hrung beeinflussen. Je nach Alter, Gr\u00f6\u00dfe, Gewicht und Aktivit\u00e4tslevel des Hundes sollte die Futtermenge, die Futterzusammensetzung und der Energiegehalt des Futters angepasst werden. <a href=\"https:\/\/www.edogs.de\/magazin\/deckrueden-edogs\/\">Welpen<\/a> und tr\u00e4chtige H\u00fcndinnen haben im Gegensatz zu erwachsenden Hunden einen erh\u00f6hten Energiebedarf.<\/p><p>Im besten Fall sollte Frischfutter gef\u00fcttert werden, doch es ist auch problemlos m\u00f6glich eine <strong>Mischung aus Nass- und Trockenfutter<\/strong> zu f\u00fcttern. Der Proteinanteil im Hundefutter sollte m\u00e4\u00dfig hoch sein, da Eiwei\u00dfe wichtig f\u00fcr die Erhaltung und Versorgung der Muskulatur sind. Au\u00dferdem bestehen, beim Menschen wie auch beim Hund, viele lebenswichtige zellul\u00e4re Strukturen aus Proteinen. Hunde gelten als omnivore Lebewesen, weshalb sie sowohl vegan als auch carnivor ern\u00e4hrt werden k\u00f6nnen. Am besten ist es, <strong>verschiedene Futtersorten auszuprobieren<\/strong>, um zu sehen, was dem Hund am bestens schmeckt und ihm am besten bekommt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4308fbe5 elementor-widget elementor-widget-text-editor\" data-id=\"4308fbe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Gesundheit &#8211; Lebenserwartung &amp; h\u00e4ufige Krankheiten<\/h2><p>Der Hollandse Smoushond besitzt eine<strong> Lebenserwartung von<\/strong> <strong>12 bis 15 Jahren<\/strong>. Ein gesunder Hund erreicht f\u00fcr gew\u00f6hnlich das Mindestalter von 12 Jahren. Es ist wichtig, dass der Hund ausreichend Bewegung bekommt und auch geistig bis ins Alter gefordert wird, um die Gesundheit des Tieres zu f\u00f6rdern und zu erhalten. Auch <strong>regelm\u00e4\u00dfige Check-Ups beim Tierarzt<\/strong> sind Pflicht.<\/p><p>Neben Kralllenschneiden und der \u00dcberpr\u00fcfung des Gewichts sind auch andere Parameter ausschlaggebend f\u00fcr die Gesundheit des Vierbeiners, die regelm\u00e4\u00dfig kontrolliert werden sollten. Der Hollandse Smoushond leidet f\u00fcr gew\u00f6hnlich unter <strong>keinen bekannten Erbkrankheiten<\/strong>. Aufgrund seiner Geschichte als Rattenf\u00e4nger und wetterbest\u00e4ndiger J\u00e4ger gilt der Hollandse Smoushond als <strong>robuste und kr\u00e4ftige Hunderasse<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39ab683e elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"39ab683e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 40 40\"><defs><style>      .cls-1 {        fill: #73b99b;        stroke-width: 0px;      }    <\/style><\/defs><path class=\"cls-1\" d=\"M20.1,28.6c.5,0,.9-.2,1.2-.5.3-.3.5-.7.5-1.2v-6.9c0-.5-.2-.9-.5-1.2-.3-.3-.7-.5-1.2-.5s-.9.2-1.2.5c-.3.3-.5.7-.5,1.2v6.9c0,.5.2.9.5,1.2.3.4.7.5,1.2.5ZM20,15.6c.5,0,1-.2,1.3-.5.4-.4.5-.8.5-1.3s-.2-1-.5-1.4c-.3-.4-.8-.6-1.3-.6s-1,.2-1.3.5c-.4.4-.5.8-.5,1.3s.2,1,.5,1.3c.3.5.8.7,1.3.7ZM20,37.3c-2.4,0-4.7-.5-6.8-1.4-2.1-.9-3.9-2.1-5.5-3.7-1.6-1.6-2.8-3.4-3.7-5.5s-1.4-4.4-1.4-6.8.5-4.7,1.4-6.8c.9-2.1,2.1-3.9,3.7-5.5s3.4-2.8,5.5-3.7,4.4-1.4,6.8-1.4,4.7.5,6.8,1.4c2.1.9,3.9,2.1,5.5,3.7,1.6,1.6,2.8,3.4,3.7,5.5s1.4,4.4,1.4,6.8-.5,4.7-1.4,6.8c-.9,2.1-2.1,3.9-3.7,5.5s-3.4,2.8-5.5,3.7c-2.1,1-4.4,1.4-6.8,1.4Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie viel kostet ein Hollandse Smoushond?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin Hollandse Smoushond kostet zwischen 700 und 1500\u20ac, abh\u00e4ngig von Ahnentafel und Zuchterfolg des jeweiligen Z\u00fcchters. (Quelle: <a href=\"https:\/\/www.edogs.de\/\">edogs<\/a>)\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54c7f06 elementor-widget elementor-widget-text-editor\" data-id=\"54c7f06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Finde deinen Hollandse Smoushond auf edogs.de<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74a10cba elementor-widget elementor-widget-html\" data-id=\"74a10cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<center><script src=\"https:\/\/www.edogs.de\/js\/edogs.getdogs.js\"><\/script>\r\n<div id=\"getDogs\"><script>\r\n\t\tgetdogs(jQuery(\"#getDogs\"), 3, \"rasse=160\", true);\r\n\t<\/script><\/div><\/center>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30fd1607 elementor-widget elementor-widget-button\" data-id=\"30fd1607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.edogs.de\/hunde\/hollaendischer-smoushund\/\" id=\"referral-magazin\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hollandse Smoushond finden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b64fd68 elementor-widget elementor-widget-text-editor\" data-id=\"1b64fd68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Pflege des Hollandse Smoushonds<\/h2><p>Die Pflege der niederl\u00e4ndischen Hunderasse gestaltet sich <strong>sehr unkompliziert<\/strong>. Der Hollandse Smoushond haart in der Regel wenig und das Fell sollte lediglich <strong>regelm\u00e4\u00dfig geb\u00fcrstet<\/strong>\u00a0werden. E ist grunds\u00e4tzlich nicht von N\u00f6ten den Hund zu baden, au\u00dfer der Hund ist nach einem Spaziergang zu dreckig. Es ist durchaus sinnvoll, den Hollands Smoushond im Sommer <strong>bei einem Hundefris\u00f6r professionell trimmen<\/strong> zu lassen, da die Hunde eine dichte und wasserabweisende Unterwolle besitzen. Durch das Ausd\u00fcnnen der Unterwolle schwitzt der Vierbeiner weniger und ist hitzebest\u00e4ndiger.<\/p><p>Im Allgemeinen ist der Hollandse Smoushond <strong>sowohl K\u00e4lte als auch <a href=\"https:\/\/www.edogs.de\/magazin\/heisse-sommertage-mit-dem-hund\/\">Hitze<\/a> gew\u00f6hnt<\/strong>, doch im Hochsommer sollte dem Hund immer ein schattiges Pl\u00e4tzchen und genug Wasser zur Verf\u00fcgung stehen.<\/p><p>Zur grundlegenden Pflege eines jeden Hundes geh\u00f6ren nat\u00fcrlich das <strong>regelm\u00e4\u00dfige Krallenschneiden und die Kontrolle von Schleimh\u00e4uten, Augen und Genitalien<\/strong> auf Fremdk\u00f6rper oder Entz\u00fcndungen. Das Schneiden der Krallen ist nicht notwendig, wenn der Hund viel auf hartem Untergrund <a href=\"https:\/\/www.edogs.de\/magazin\/wie-oft-muss-ein-hund-raus\/\">spazieren<\/a> geht, da sich die Krallen in diesem Fall von selbst abnutzen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41636851 elementor-widget elementor-widget-text-editor\" data-id=\"41636851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Hollandse Smoushond &#8211; Aktivit\u00e4ten und Training<\/h2><p>Der Hollandse Smoushond ist <strong>gut trainierbar<\/strong> und <strong>gut f\u00fcr Familien mit Kindern geeignet<\/strong>. Er besitzt zwar als <a href=\"https:\/\/www.edogs.de\/magazin\/jagdhunde-wahre-spezialisten-in-der-natur\/\">Jagdhund<\/a> ein eigenst\u00e4ndiges Wesen, dennoch fokussiert er sich gerne auf seinen Besitzer. Im Training tritt er freudig und intelligent auf, doch es ist Geduld gefragt. Der Hollandse Smoushond braucht <strong>klare und konsequente F\u00fchrung<\/strong>, damit er sich auf seinen Hundef\u00fchrer verlassen kann. Er testet zwar einerseits gerne seine Grenzen aus, doch folgt andererseits klaren Kommandos widerstandslos. Er ist gut mit Leckerlis und Spielzeug zu motivieren, was im Training einen Vorteil bietet.<\/p><p>Der <strong>Spieltrieb des Holl\u00e4nders ist sehr ausgepr\u00e4gt<\/strong>, was der Besitzer sich zunutze machen kann. Gerne erarbeitet sich der Hollandse Smoushond seine Belohnung und findet Spa\u00df an abwechslungsreichen Aktivit\u00e4ten. Der mittelgro\u00dfe Hund eignet sich au\u00dferdem f\u00fcr <strong>diverse <a href=\"https:\/\/www.edogs.de\/magazin\/hundewissen\/hundesport\/\">Hundesportarten<\/a><\/strong>. Dazu z\u00e4hlen unter anderem Flyball, <a href=\"https:\/\/www.edogs.de\/magazin\/was-ist-agility\/\">Agility<\/a>, Breitensport oder <a href=\"https:\/\/www.edogs.de\/magazin\/mantrailing\/\">Mantrailing<\/a>. F\u00fcr <a href=\"https:\/\/www.edogs.de\/magazin\/obedience\/\">Obedience<\/a> eignet sich der Jagdhund m\u00e4\u00dfig, am liebsten macht er sich auf die Suche nach F\u00e4hrten.<\/p><p>Der Hollandse Smoushond ist sehr gerne in der Natur und erlebt gerne Abenteuer. Er ist ein Freund von Bewegung und Abwechslung in seinem Alltag. Dieser Vierbeiner ben\u00f6tigt <strong>mindestens zwei Stunden Bewegung am Tag<\/strong> und reichlich Zeit, um sich auszutoben. Egal ob aus <a href=\"https:\/\/www.edogs.de\/magazin\/fahrradfahren-mit-hund\/\">Radtouren<\/a>, Wanderungen oder Inlineskaten, der Holl\u00e4nder ist mit Begeisterung dabei. Aufgrund seiner Gr\u00f6\u00dfe ist es jedoch wichtig, dem Hund nach dem Laufen l\u00e4ngerer Strecken regelm\u00e4\u00dfige Pausen zu erm\u00f6glichen. Es ist auch empfehlenswert, einen Fahrradkorb am Fahrrad zu montieren, damit der Hund sich gegebenenfalls ausruhen kann. Auch als <strong>Begleitung zu Pferd<\/strong> ist der Hollandse Smoushond geeignet, sofern er bereits als <a href=\"https:\/\/www.edogs.de\/magazin\/ab-wann-duerfen-welpen-treppen-laufen\/\">Welpe<\/a> an die Tiere und das Begleiten gew\u00f6hnt wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e9d63a2 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2e9d63a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Ebene_1\" data-name=\"Ebene 1\" viewBox=\"0 0 40 40\"><defs><style>      .cls-1 {        fill: #73b99b;        stroke-width: 0px;      }    <\/style><\/defs><path class=\"cls-1\" d=\"M20.1,28.6c.5,0,.9-.2,1.2-.5.3-.3.5-.7.5-1.2v-6.9c0-.5-.2-.9-.5-1.2-.3-.3-.7-.5-1.2-.5s-.9.2-1.2.5c-.3.3-.5.7-.5,1.2v6.9c0,.5.2.9.5,1.2.3.4.7.5,1.2.5ZM20,15.6c.5,0,1-.2,1.3-.5.4-.4.5-.8.5-1.3s-.2-1-.5-1.4c-.3-.4-.8-.6-1.3-.6s-1,.2-1.3.5c-.4.4-.5.8-.5,1.3s.2,1,.5,1.3c.3.5.8.7,1.3.7ZM20,37.3c-2.4,0-4.7-.5-6.8-1.4-2.1-.9-3.9-2.1-5.5-3.7-1.6-1.6-2.8-3.4-3.7-5.5s-1.4-4.4-1.4-6.8.5-4.7,1.4-6.8c.9-2.1,2.1-3.9,3.7-5.5s3.4-2.8,5.5-3.7,4.4-1.4,6.8-1.4,4.7.5,6.8,1.4c2.1.9,3.9,2.1,5.5,3.7,1.6,1.6,2.8,3.4,3.7,5.5s1.4,4.4,1.4,6.8-.5,4.7-1.4,6.8c-.9,2.1-2.1,3.9-3.7,5.5s-3.4,2.8-5.5,3.7c-2.1,1-4.4,1.4-6.8,1.4Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tWie alt wird ein Hollandse Smoushond?\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEin Hollandse Smoushond besitzt eine Lebenserwartung zwischen 12 und 15 Jahren.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15c98652 elementor-widget elementor-widget-text-editor\" data-id=\"15c98652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Gut zu wissen: Besonderheiten des Hollandse Smoushonds<\/h2><p>Charakteristisch f\u00fcr den Hollandse Smoushond ist auf jeden Fall sein <strong>strubbeliges Erscheinungsbild<\/strong>, das ihm sein <strong>raues und verspieltes Aussehen<\/strong> verleiht. Das Fell steht in vielen F\u00e4llen wild in alle Richtungen ab und macht den Holl\u00e4nder umso liebenswerter.<\/p><p>Eine weitere Besonderheit des Hollandse Smoushond ist sein <strong>ausgepr\u00e4gter Spieltrieb<\/strong> und seine Kinderfreudlichkeit. Der <a href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/mittelgrosse-hunde\/\">mittelgro\u00dfe<\/a> Jagdhund tritt auch den Kleinsten der Familie mit Geduld und Respekt gegen\u00fcber. Es ist wichtig, den Kindern den richtigen Umgang mit dem Hund beizubringen, um ein harmonisches Familienleben zu sichern. Wer auf der Suche nach einem aktiven und freundlichen Familien- und Begleithund ist, der ist mit dem Hollandse Smoushond gut beraten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4279cc27 elementor-widget elementor-widget-text-editor\" data-id=\"4279cc27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Nachteile des Hollandse Smoushonds<\/h2><p>Ein Nachteil des Hollandse Smoushond ist sein <strong>ausgepr\u00e4gter Jagdtrieb<\/strong>. In Verbindung mit seinem eigenst\u00e4ndigen Wesen kann ein <strong>Spaziergang ohne Leine bei fehlender Erziehung zum Problem werden<\/strong>. Doch obwohl der Holl\u00e4nder sehr gerne Eigenverantwortung \u00fcbernimmt, l\u00e4sst er sich gut f\u00fchren und reagiert aufmerksam und gut auf Kommandos. Es ist wichtig, dass mit der Erziehung des Hundes so fr\u00fch wie m\u00f6glich begonnen wird. So kann ein reibungsloser Trainingsablauf und eine gute Erziehung des Hundes sichergestellt werden. Ansonsten gilt der Hollandse Smoushond als eine sehr unkomplizierte, pflegeleichte und fr\u00f6hliche Hunderasse, die Freude am Leben verspr\u00fcht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72e00128 elementor-widget elementor-widget-text-editor\" data-id=\"72e00128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Passt der Hollandse Smoushond zu mir?<\/h2><p>Der mittelgro\u00dfe Jagdhund ben\u00f6tigt in jedem Fall jemanden, der <strong>Freude an Bewegung<\/strong> und der Besch\u00e4ftigung mit dem Hund findet. <strong>Lange Spazierg\u00e4nge, regelm\u00e4\u00dfiges Training sowie Kuschelstunden<\/strong> auf der Couch sollten Fixpunkte im Leben eines Hollandse Smoushond Besitzers sein. Aufgrund seiner Gr\u00f6\u00dfe ist es m\u00f6glich, den Holl\u00e4nder sowohl in einer <strong>kleinen Wohnung als auch in einem gro\u00dfen Haus <\/strong>zu halten. Am besten eignet sich ein Grundst\u00fcck, das Auslaufm\u00f6glichkeit f\u00fcr den Hund bietet.<\/p><p>Der Hollandse Smoushond <strong>vertr\u00e4gt sich mittelgut mit Artgenossen<\/strong>, kann jedoch bei fr\u00fcher Gew\u00f6hnung an andere Haustiere gemeinsam mit anderen Tieren gehalten werden. Durch seinen Jagdtrieb ist davon abzuraten Nagetiere oder andere Kleintiere im selben Haushalt zu halten. Kindern gegen\u00fcber begegnet der mittelgro\u00dfe Hund mit Respekt, Vorsicht und Herzlichkeit. Der Jagdhund ist durchaus anh\u00e4nglich und verspielt und f\u00fchlt sich am wohlsten, wenn er aktiv am <a href=\"https:\/\/www.edogs.de\/magazin\/familienhund\/\">Familienleben<\/a> teilnehmen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der Hollandse Smoushond ist eine aus den Niederlanden stammende Hunderasse. Sie ist durch die FCI&hellip;<\/p>\n","protected":false},"author":68,"featured_media":35245,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"class_list":["post-13844","hunderassen","type-hunderassen","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung<\/title>\n<meta name=\"description\" content=\"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief &amp; Infos \u2714 Charakter &amp; Wesen \u2714 Haltung &amp; Pflege \u2714 Tipps &amp; Bilder \u27bd\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung\" \/>\n<meta property=\"og:description\" content=\"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief &amp; Infos \u2714 Charakter &amp; Wesen \u2714 Haltung &amp; Pflege \u2714 Tipps &amp; Bilder \u27bd\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/\" \/>\n<meta property=\"og:site_name\" content=\"edogs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T09:32:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/hollandse-smoushond.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/\",\"name\":\"Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/hollandse-smoushond.jpg\",\"datePublished\":\"2017-11-06T15:10:50+00:00\",\"dateModified\":\"2025-04-30T09:32:22+00:00\",\"description\":\"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief & Infos \u2714 Charakter & Wesen \u2714 Haltung & Pflege \u2714 Tipps & Bilder \u27bd\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/hollandse-smoushond.jpg\",\"contentUrl\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/wp-content\\\/uploads\\\/hollandse-smoushond.jpg\",\"width\":1500,\"height\":800,\"caption\":\"Hollandse Smoushound\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/hunderassen\\\/hollandse-smoushond\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hollandse Smoushond\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"name\":\"edogs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#organization\",\"name\":\"edogs\",\"url\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"edogs\"},\"image\":{\"@id\":\"https:\\\/\\\/www.edogs.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung","description":"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief & Infos \u2714 Charakter & Wesen \u2714 Haltung & Pflege \u2714 Tipps & Bilder \u27bd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/","og_locale":"de_DE","og_type":"article","og_title":"Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung","og_description":"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief & Infos \u2714 Charakter & Wesen \u2714 Haltung & Pflege \u2714 Tipps & Bilder \u27bd","og_url":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/","og_site_name":"edogs","article_modified_time":"2025-04-30T09:32:22+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/hollandse-smoushond.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/","url":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/","name":"Hollandse Smoushound - Steckbrief, Charakter, Wesen und Haltung","isPartOf":{"@id":"https:\/\/www.edogs.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/#primaryimage"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/#primaryimage"},"thumbnailUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/hollandse-smoushond.jpg","datePublished":"2017-11-06T15:10:50+00:00","dateModified":"2025-04-30T09:32:22+00:00","description":"Der Hollandse Smoushond im Rasseportrait \u2714 Steckbrief & Infos \u2714 Charakter & Wesen \u2714 Haltung & Pflege \u2714 Tipps & Bilder \u27bd","breadcrumb":{"@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/#primaryimage","url":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/hollandse-smoushond.jpg","contentUrl":"https:\/\/www.edogs.de\/magazin\/wp-content\/uploads\/hollandse-smoushond.jpg","width":1500,"height":800,"caption":"Hollandse Smoushound"},{"@type":"BreadcrumbList","@id":"https:\/\/www.edogs.de\/magazin\/hunderassen\/hollandse-smoushond\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.edogs.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Hollandse Smoushond"}]},{"@type":"WebSite","@id":"https:\/\/www.edogs.de\/magazin\/#website","url":"https:\/\/www.edogs.de\/magazin\/","name":"edogs","description":"","publisher":{"@id":"https:\/\/www.edogs.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.edogs.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.edogs.de\/magazin\/#organization","name":"edogs","url":"https:\/\/www.edogs.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"edogs"},"image":{"@id":"https:\/\/www.edogs.de\/magazin\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/hunderassen\/13844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/hunderassen"}],"about":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/types\/hunderassen"}],"author":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/users\/68"}],"replies":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/comments?post=13844"}],"version-history":[{"count":5,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/hunderassen\/13844\/revisions"}],"predecessor-version":[{"id":83581,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/hunderassen\/13844\/revisions\/83581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media\/35245"}],"wp:attachment":[{"href":"https:\/\/www.edogs.de\/magazin\/wp-json\/wp\/v2\/media?parent=13844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}